{"id":5739,"count":4,"description":"","link":"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/","name":"Abstraction","slug":"abstraction","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Abstraction - Egidi MadeinItaly<\/title>\n<meta name=\"description\" content=\"Corrente artistica sviluppatasi all&#039;inizio del 900 che nega la rappresentazione della realt\u00e0 usando concetti rappresentati attraverso le linee, i colori e le forme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abstraction Archivi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/\" \/>\n<meta property=\"og:site_name\" content=\"Egidi MadeinItaly\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/tag\\\/abstraction\\\/\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/tag\\\/abstraction\\\/\",\"name\":\"Abstraction - Egidi MadeinItaly\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/#website\"},\"description\":\"Corrente artistica sviluppatasi all'inizio del 900 che nega la rappresentazione della realt\u00e0 usando concetti rappresentati attraverso le linee, i colori e le forme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/tag\\\/abstraction\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/tag\\\/abstraction\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abstraction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/\",\"name\":\"Egidi MadeinItaly\",\"description\":\"Fine Art\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Abstraction - Egidi MadeinItaly","description":"Corrente artistica sviluppatasi all'inizio del 900 che nega la rappresentazione della realt\u00e0 usando concetti rappresentati attraverso le linee, i colori e le forme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/","og_locale":"fr_FR","og_type":"article","og_title":"Abstraction Archivi","og_url":"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/","og_site_name":"Egidi MadeinItaly","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/","url":"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/","name":"Abstraction - Egidi MadeinItaly","isPartOf":{"@id":"https:\/\/egidimadeinitaly.com\/fr\/#website"},"description":"Corrente artistica sviluppatasi all'inizio del 900 che nega la rappresentazione della realt\u00e0 usando concetti rappresentati attraverso le linee, i colori e le forme.","breadcrumb":{"@id":"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/egidimadeinitaly.com\/fr\/tag\/abstraction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egidimadeinitaly.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/egidimadeinitaly.com\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Abstraction"}]},{"@type":"WebSite","@id":"https:\/\/egidimadeinitaly.com\/fr\/#website","url":"https:\/\/egidimadeinitaly.com\/fr\/","name":"Egidi MadeinItaly","description":"Fine Art","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egidimadeinitaly.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/tags\/5739"}],"collection":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/posts?tags=5739"},{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/artisti?tags=5739"},{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/evento?tags=5739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}