{"id":103408,"date":"2021-09-09T14:18:53","date_gmt":"2021-09-09T13:18:53","guid":{"rendered":"http:\/\/egidimadeinitaly.demonewlogic.it\/artisti\/fabio-fabbi\/"},"modified":"2025-03-02T10:22:35","modified_gmt":"2025-03-02T09:22:35","slug":"fabio-fabbi","status":"publish","type":"artisti","link":"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/","title":{"rendered":"Fabio Fabbi"},"content":{"rendered":"<p>Parmi les rares tableaux de Fabio Fabbi dont nous connaissons l\u2019emplacement, il y a deux huiles sur carton, \u00ab Mosqu\u00e9e \u00bb (Bologne, Gall. com. d&rsquo;art moderne) et un Paysage bolonais intitul\u00e9 \u00ab Quatre tours \u00bb (propri\u00e9t\u00e9 de la Cassa di risparmio, cf. Varignana, 1972). Le reste des \u0153uvres de Fabio Fabbi dont la plupart font partie de collections priv\u00e9es, sont difficiles \u00e0 trouver, notamment en raison de leur titre impr\u00e9cis et des sujets r\u00e9p\u00e9titifs. La principale source de documentation photographique reste le catalogue de l\u2019exposition qui organis\u00e9e en 1981 \u00e0 la galerie \u00ab Il 2 di Quadri \u00bb \u00e0 Bologne, qui poss\u00e8de plusieurs \u0153uvres de Fabio Fabbi.<\/p>\n<p>En 1888, Fabio Fabbi expose <em>Un terrazzo ad Alessandria<\/em> au Cercle des artistes de Florence (ill. in Stivani-Borgogelli, 1981, planche XI), d\u2019un style photographique marqu\u00e9, \u00ab Donna araba \u00bb, \u00ab Il vasaio \u00bb, \u00ab Vecchio musulmano \u00bb.<\/p>\n<p>\u00c0 l&rsquo;exposition internationale de Munich, il est r\u00e9compens\u00e9 pour ses tableaux intitul\u00e9s \u00ab <em>La vendita di una schiava<\/em> \u00bb (ibid., planche V) et \u00ab <em>I sette peccati mortali<\/em> \u00bb.<\/p>\n<p>La d\u00e9coration du fumoir de la villa Sorani \u00e0 Florence avec six grandes d\u00e9trempes orientalistes peut \u00eatre dat\u00e9e de la fin des ann\u00e9es 1880 , ainsi que L&rsquo;\u00c9gypte, un album de souvenirs et de dessins originaux publi\u00e9 par Alinari, (Florence s.d. De Gubernatis, 1889, p. 190).<\/p>\n<p>En 1896, il collabore avec la revue florentine \u00ab Fiammetta \u00bb, dont il r\u00e9alise l\u2019affiche en 1897.<\/p>\n<p>Au cours de ces ann\u00e9es, il se consacre \u00e9galement \u00e0 la peinture religieuse. En effet, \u00e0 c\u00f4t\u00e9 du \u00ab Santone musulmano \u00bb de 1896 , il pr\u00e9sente \u00ab l&rsquo;Annonciazione \u00bb et le \u00ab Cristo deriso \u00bb \u00e0 l&rsquo;exposition de l&rsquo;art et des fleurs de Florence (cf. L&rsquo;Ill. ital., 11 avril 1897, pp. 232, 238).<\/p>\n<p>Il a toujours entretenu des rapports constants et anim\u00e9s avec L&rsquo;\u00c9milie-Romagne. Avec son fr\u00e8re Alberto, il signe un \u00ab San Giovanni decollato \u00bb pour la basilique de San Giovanni in Persiceto, probablement r\u00e9alis\u00e9 \u00e0 la fin du si\u00e8cle, et un Sacro-Cuore con San Antonio abate e S. Antonio Maria Zaccaria, fondateur de l\u2019ordre des Barnabites (peint en 1902) pour l\u2019\u00e9glise Sant \u2018Antonio Abate de Bologne.<\/p>\n<p>En 1893, il est nomm\u00e9 professeur \u00e0 l\u2019Acad\u00e9mie des Beaux-arts de Florence, et en 1894 \u00e0 l\u2019Acad\u00e9mie de Bologne. En 1898, il est nomm\u00e9 chevalier de la Couronne d&rsquo;Italie.<\/p>\n<p>Entre 1898 et 1905, il est l\u2019auteur de nombreuses cartes postales, dont les s\u00e9ries Divine Com\u00e9die, Finis seculi XIX, Domine (cf. Arrasich, 1985).<\/p>\n<p>En 1899, il participe au premier concours organis\u00e9 par Vittorio Alinari, qui a pour th\u00e8me \u00ab La Vierge \u00e0 l&rsquo;Enfant \u00bb, o\u00f9 il pr\u00e9sente deux tableaux (\u00ab Mammina \u00bb et la \u00ab Madonna alla spiga \u00bb).<\/p>\n<p>Pendant le 1900, il r\u00e9alise des dessins humoristiques pour la revue bolonaise <em>Italia ride<\/em> ; il dessine les planches de Firenze sotterranea (Florence souterraine) de Jarro [Giulio Piccini], o\u00f9 il exprime une veine subtilement r\u00e9aliste et humanitaire, interpr\u00e9tant le texte \u00ab avec un regard \u00e0 la fois photographique et m\u00e9tamorphos\u00e9 \u00bb (Pallottino, 1988, p. 190).<\/p>\n<p>&nbsp;<\/p>\n<p>En 1902, il participe au deuxi\u00e8me concours, qui a pour th\u00e8me \u00ab La vie de la Vierge \u00bb, (avec G. Costetti, A. Martini et G. Kienerk) et enfin, la m\u00eame ann\u00e9e, il r\u00e9alise trois peintures \u00e0 l\u2019huile consacr\u00e9es au Chant XIII du Paradis, pour le livre <em>La Divine Com\u00e9die illustr\u00e9e \u00e0 nouveau par des artistes italiens<\/em>. Fabio Fabbi est \u00e9galement l\u2019auteur du grand tableau intitul\u00e9 \u00ab Morte di Anita Garibaldi \u00bb, datant du d\u00e9but du XXe si\u00e8cle (Florence, Biblioth\u00e8que et Archives du Risorgimento).<\/p>\n<p>En 1906, il pr\u00e9sente des mod\u00e8les de m\u00e9dailles r\u00e9alis\u00e9s avec la technique de la cire perdue, \u00e0 l\u2019Exposition internationale du Sempione \u00e0 Milan.<\/p>\n<p>En 1911, il participe \u00e0 l&rsquo;Exposition internationale de l&rsquo;art chr\u00e9tien moderne \u00e0 Paris, \u00e0 c\u00f4t\u00e9 des artistes disparus P. Puvis de Chavannes, E. Carri\u00e8re et M. Denis. En tant que collaborateur de la maison d\u2019\u00e9dition Bemporad de Florence, il illustre, avec d\u2019autres dessinateurs, principalement toscans, la trilogie de L. Rasi (Le livre des monologues, Le second livre des monologues, Milan, respectivement de 1888 et 1893, et Le livre des anecdotes, Mod\u00e8ne 1890).<\/p>\n<p>Il a illustr\u00e9 plus d\u2019une centaine d\u2019ouvrages, pr\u00e9f\u00e9rant, outre les classiques de la litt\u00e9rature publi\u00e9s par la maison d\u2019\u00e9dition Nerbini de Florence (G. Casanova, M\u00e9moires, 1920 ; G. Boccace, D\u00e9cam\u00e9ron, 1932 ; T. Tasso, La J\u00e9rusalem d\u00e9livr\u00e9e, 1934 ; Hom\u00e8re, L\u2019Odyss\u00e9e, trad. de V. Monti, 1934), les romans d&rsquo;aventure, notamment de Salgari, \u00ab\u00a0 qu\u2019il sut impr\u00e9gner de l\u2019atmosph\u00e8re particuli\u00e8re et gracieuse d\u2019un r\u00eave oriental \u00bb (Faeti, 1972) qui se caract\u00e9risent par la ductilit\u00e9 technique et chromatique dans l&rsquo;utilisation de la d\u00e9trempe et de l&rsquo;aquarelle, et une l\u00e9g\u00e8ret\u00e9 narrative originale.<\/p>\n<p>Parmi les i livres pour enfants qu\u2019il a illustr\u00e9s,\u00a0 rappelons notamment ceux de Louisa May Alcott, \u00ab Petits hommes \u00bb Florence 1910-1911, et \u00ab Petites femmes \u00bb en 1916.<\/p>\n<p>En 1936, il quitte Bologne et s\u2019installe \u00e0 Casalecchio di Reno (prov. de Bologne) o\u00f9 il meurt le 24 septembre 1945.<\/p>\n<h5>Sources et bibliographie : A. De Gubernatis, Diz. degli artisti ital. viventi&#8230;, Florence 1889, pp. 189 sq. ; Exposition Vittorio Alinari, Florence 1900, n. 85, 89 ; Exposition des peintres \u00e9miliens du XIXe si\u00e8cle, organis\u00e9e par l&rsquo;Acad\u00e9mie Cl\u00e9mentine, Bologne 1955, p. 66 ; I. Cinti, Hommage au XIXe si\u00e8cle bolonais (catal.), Bologne 1957, p. 11 ; M. Giardelli, I macchiaioli e l&rsquo;epoca loro, Milan 1958, pp. 164, 209, 258, 262, 310 ; Il manifesto ital. nel centenario del manifesto litografico (catal.), Milan 1965, p. 35, fig. 74 ; T. Fanti, in Galerie Caldarese, Catalogue exposition postume, Bologne 1968\u00a0 ; E. Contini, F. F. dall&rsquo;Egitto con amore, in Qui Bologna, 31 oct. 1968, n\u00b0 27 ; C. Ricci-G. Zucchini, Guide de Bologna, Bologne 1968, p. 212 ; F. Varignana, in Les collections d&rsquo;art de la Cassa di risparmio de Bologne. I dipinti, sous la direction de A. Emiliani, Bologne 1972, pp. 457 s. ; A. Faeti, Guardare le figure, Turin 1972, pp. 162 sqq., 388 sq. ; F. Cristofori, Bologna come rideva. I giornali satirici dal 1859 al 1924, Bologne 1973, ad Ind. ; E. Gottarelli, \u00ab Italia Ride \u00bb. Il miracolo del liberty bolognese, Bologne 1974, p. 63 ; \u0152uvres du XX si\u00e8cle dans les collections d\u2019art municipales, Bologne 1975, p. 75 ; L\u2019art nouveau \u00e0 Bologne et en \u00c9milie-Romagne. Architecture, arts appliqu\u00e9s et graphisme, peinture et sculpture, Bologne 1977, p. 287 ; C. Cresti, Firenze 1896-1915. La stagione del liberty, Florence 1978, pp. 18, 320 ; M. Pasquali, A. Bastianini et F. F., in E nell&rsquo;idolo suo si trasmutava. La Divina Commedia nuovamente illustrata da artisti italiani (catal.), Bologne 1979, pp. 97 sq. ; E. Gaibazzi, Catalogue ital. des cartes postales d&rsquo;\u00e9poque, Bologne 1979, pp. n.n. ; Alfonso Rubbiani: I veri e i falsi storici, sous la direction de F. Solmi-M. Dezzi Bardeschi (catal.), Bologne 1981, pp. 97, 468, 471 ; P. Stivani-A. Borgogelli, F.F. (catal.), Bologne 1981 ; Pittura ital. dell&rsquo;Ottocento. Le opere pittoriche vendute in Italia e all&rsquo;estero, Milan 1984, p. 75 ; G. Fanelli-E. Godoli, La cartolina art nouveau, Florence 1985, p. 335 ; Artisti fra &lsquo;800 e &lsquo;900. Una raccolta bolognese, sous la direction de F. Solmi-M. Pasquali, Bologne 1985, pp. 38 sqq. ; Almanacchi e strenne dell&rsquo;Ottocento toscano (catal.), sous la direction de\u00a0 R. Maini, Florence 1985, pp. 57 sqq. ; F. Arrasich, Catalogo delle cartoline ital., Suppl. \u00e0 La Cartolina, 1985, n\u00b0 2, p. 56 ; P. Pallottino, Storia dell&rsquo;illustrazione italiana [1988], Bologne 1991, ad Indicem ; A. Faeti-P. Pallottino, L&rsquo;illustrazione nel romanzo popolare. Tavole originali dalla coll. Rava (1907-1938), Turin 1988, p. 37, planches 10 \u00e0 23 ; L&rsquo;eterno femminino (catal. Galerie d&rsquo;art Eleuteri), Rome s.d. [ma 1989], pp. 69 sq. ; G. Fanelli-E. Godoli, Diz. degli illustratori simbolisti e art nouveau, Rome 1990, I, p. 165 ; Il valore dei dipinti dell\u2019Ottocento, Turin 1990, pp. 150 sq. ; S. Paolo di Ravone 990-1990, Bologne 1990 ; I best seller del Ventennio. Il regime e il libro di massa, sous la direction de G. De Donato-V. Gazzola Stacchini, Milan 1992 ; Il ventennio in copertina, sous la direction d\u2019E. Detti, Rome 1991, pp. n. n. ; M. Vannucci, Firenze Ottocento, Milan 1992, p. 263 ; U. Thieme-F. Becker, K\u00fcnstlerlexikon, XI, pp. 146 sq. ; A. M. Comanducci, Diz. illustrato dei pittori e incisori ital. moderni (1800-1900), Milan 1945, I, p. 244 ; Dizionario enciclopedico Bolaffi dei pittori e degli incisori italiani&#8230;, Turin 1973, IV, p. 255.<\/h5>\n<p>Avec l\u2019aimable autorisation des archives Fabio Fabbi<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le critique Paolo Stivani l&rsquo;a d\u00e9crit comme \u00ab\u00a0un illusionniste et un affabulateur d&rsquo;images\u00a0\u00bb.<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","format":"standard","meta":{"_acf_changed":false},"tags":[6508],"class_list":["post-103408","artisti","type-artisti","status-publish","format-standard","hentry","tags-f"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fabio Fabbi - Egidi MadeinItaly<\/title>\n<meta name=\"description\" content=\"Le peintre Fabio Fabbi (1861-1946) est surtout connu pour ses \u0153uvres orientalistes, riches en couleurs et en d\u00e9tails.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabio Fabbi\" \/>\n<meta property=\"og:description\" content=\"Le critique Paolo Stivani l&#039;a d\u00e9crit comme &quot;un illusionniste et un affabulateur d&#039;images&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/\" \/>\n<meta property=\"og:site_name\" content=\"Egidi MadeinItaly\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/egidimadeinitaly\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T09:22:35+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/artisti\\\/fabio-fabbi\\\/\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/artisti\\\/fabio-fabbi\\\/\",\"name\":\"Fabio Fabbi - Egidi MadeinItaly\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-09-09T13:18:53+00:00\",\"dateModified\":\"2025-03-02T09:22:35+00:00\",\"description\":\"Le peintre Fabio Fabbi (1861-1946) est surtout connu pour ses \u0153uvres orientalistes, riches en couleurs et en d\u00e9tails.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/artisti\\\/fabio-fabbi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/artisti\\\/fabio-fabbi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/artisti\\\/fabio-fabbi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fabio Fabbi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/\",\"name\":\"Egidi MadeinItaly\",\"description\":\"Fine Art\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egidimadeinitaly.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fabio Fabbi - Egidi MadeinItaly","description":"Le peintre Fabio Fabbi (1861-1946) est surtout connu pour ses \u0153uvres orientalistes, riches en couleurs et en d\u00e9tails.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/","og_locale":"fr_FR","og_type":"article","og_title":"Fabio Fabbi","og_description":"Le critique Paolo Stivani l'a d\u00e9crit comme \"un illusionniste et un affabulateur d'images\".","og_url":"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/","og_site_name":"Egidi MadeinItaly","article_publisher":"https:\/\/www.facebook.com\/egidimadeinitaly\/","article_modified_time":"2025-03-02T09:22:35+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/","url":"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/","name":"Fabio Fabbi - Egidi MadeinItaly","isPartOf":{"@id":"https:\/\/egidimadeinitaly.com\/fr\/#website"},"datePublished":"2021-09-09T13:18:53+00:00","dateModified":"2025-03-02T09:22:35+00:00","description":"Le peintre Fabio Fabbi (1861-1946) est surtout connu pour ses \u0153uvres orientalistes, riches en couleurs et en d\u00e9tails.","breadcrumb":{"@id":"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/egidimadeinitaly.com\/fr\/artisti\/fabio-fabbi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egidimadeinitaly.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Fabio Fabbi"}]},{"@type":"WebSite","@id":"https:\/\/egidimadeinitaly.com\/fr\/#website","url":"https:\/\/egidimadeinitaly.com\/fr\/","name":"Egidi MadeinItaly","description":"Fine Art","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egidimadeinitaly.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/artisti\/103408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/artisti"}],"about":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/types\/artisti"}],"wp:attachment":[{"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/media?parent=103408"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/tags?post=103408"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/fr\/wp-json\/wp\/v2\/tags?post=103408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}