{"id":83359,"date":"2024-01-15T15:24:09","date_gmt":"2024-01-15T14:24:09","guid":{"rendered":"https:\/\/egidimadeinitaly.com\/ecomsite\/product\/pair-of-gueridons-in-gilded-wood-italy-19th-century\/"},"modified":"2023-11-20T15:22:04","modified_gmt":"2023-11-20T14:22:04","slug":"pair-of-gilded-wood-wall-brackets","status":"publish","type":"product","link":"https:\/\/egidimadeinitaly.com\/en\/negozio\/works-of-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/","title":{"rendered":"Pair of gilded wood wall brackets"},"content":{"rendered":"<div class=\"accordion_content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\">\n<div class=\"accordion_content_inner\">\n<p>Pair of gueridons in gilded, lacquered wood.<br \/>\nFlorence late 18th century.<br \/>\nThe bases of these elegant consoles are a weave of leaf, flower, and branch elements forming a visually striking flowering bush.<br \/>\nThe leaves and flowers are gold leaf, and the branches are lacquered in beige, so well-crafted that the effect is highly realistic.<br \/>\nThe lacquered and gilded wood base is triangular. The front is embellished with a shell-shaped carved frieze.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pair of gueridons in gilded, lacquered wood.<\/p>\n<p>Their size makes them perfect for either wall consoles or floor tables, such as side tables by a bed or a sofa.<\/p>\n","protected":false},"featured_media":116815,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[6405,6491],"product_tag":[1648],"class_list":{"0":"post-83359","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-antique-work-of-art-en","7":"product_cat-works-of-art","8":"product_tag-gilt-wood","10":"first","11":"outofstock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pair of gilded wood wall brackets - Egidi MadeinItaly<\/title>\n<meta name=\"description\" content=\"Pair of gueridons in gilded wood Florence late 18th century perfect as nightstands or next to a sofa available only at Egidi MadeinItaly E-Commerce\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pair of gilded wood wall brackets\" \/>\n<meta property=\"og:description\" content=\"Pair of gueridons in gilded, lacquered wood.  Their size makes them perfect for either wall consoles or floor tables, such as side tables by a bed or a sofa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/\" \/>\n<meta property=\"og:site_name\" content=\"Egidi MadeinItaly\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/egidimadeinitaly\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/egidimadeinitaly.com\/wp-content\/uploads\/2020\/02\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1984\" \/>\n\t<meta property=\"og:image:height\" content=\"1984\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/works-of-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product\\\/antique-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/\",\"name\":\"Pair of gilded wood wall brackets - Egidi MadeinItaly\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product\\\/antique-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product\\\/antique-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg\",\"datePublished\":\"2024-01-15T14:24:09+00:00\",\"description\":\"Pair of gueridons in gilded wood Florence late 18th century perfect as nightstands or next to a sofa available only at Egidi MadeinItaly E-Commerce\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product\\\/antique-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product\\\/antique-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product\\\/antique-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/#primaryimage\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg\",\"contentUrl\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg\",\"width\":1984,\"height\":1984,\"caption\":\"Pair of Demi-Lune Console Tables in Gilded Wood\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product\\\/antique-art\\\/antique-work-of-art-en\\\/pair-of-gilded-wood-wall-brackets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Works of art\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product-category\\\/works-of-art\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Antique work of art\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product-category\\\/works-of-art\\\/antique-work-of-art-en\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pair of gilded wood wall brackets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\",\"name\":\"Egidi MadeinItaly\",\"description\":\"Fine Art\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pair of gilded wood wall brackets - Egidi MadeinItaly","description":"Pair of gueridons in gilded wood Florence late 18th century perfect as nightstands or next to a sofa available only at Egidi MadeinItaly E-Commerce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/","og_locale":"en_US","og_type":"article","og_title":"Pair of gilded wood wall brackets","og_description":"Pair of gueridons in gilded, lacquered wood.  Their size makes them perfect for either wall consoles or floor tables, such as side tables by a bed or a sofa.","og_url":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/","og_site_name":"Egidi MadeinItaly","article_publisher":"https:\/\/www.facebook.com\/egidimadeinitaly\/","og_image":[{"width":1984,"height":1984,"url":"https:\/\/egidimadeinitaly.com\/wp-content\/uploads\/2020\/02\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egidimadeinitaly.com\/en\/negozio\/works-of-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/","url":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/","name":"Pair of gilded wood wall brackets - Egidi MadeinItaly","isPartOf":{"@id":"https:\/\/egidimadeinitaly.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/#primaryimage"},"image":{"@id":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/#primaryimage"},"thumbnailUrl":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2020\/02\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg","datePublished":"2024-01-15T14:24:09+00:00","description":"Pair of gueridons in gilded wood Florence late 18th century perfect as nightstands or next to a sofa available only at Egidi MadeinItaly E-Commerce","breadcrumb":{"@id":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/#primaryimage","url":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2020\/02\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg","contentUrl":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2020\/02\/coppia-mensole-antiche-da-muro-in-legno-dorato.jpg","width":1984,"height":1984,"caption":"Pair of Demi-Lune Console Tables in Gilded Wood"},{"@type":"BreadcrumbList","@id":"https:\/\/egidimadeinitaly.com\/en\/product\/antique-art\/antique-work-of-art-en\/pair-of-gilded-wood-wall-brackets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egidimadeinitaly.com\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/egidimadeinitaly.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Works of art","item":"https:\/\/egidimadeinitaly.com\/en\/product-category\/works-of-art\/"},{"@type":"ListItem","position":4,"name":"Antique work of art","item":"https:\/\/egidimadeinitaly.com\/en\/product-category\/works-of-art\/antique-work-of-art-en\/"},{"@type":"ListItem","position":5,"name":"Pair of gilded wood wall brackets"}]},{"@type":"WebSite","@id":"https:\/\/egidimadeinitaly.com\/en\/#website","url":"https:\/\/egidimadeinitaly.com\/en\/","name":"Egidi MadeinItaly","description":"Fine Art","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egidimadeinitaly.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product\/83359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/media\/116815"}],"wp:attachment":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/media?parent=83359"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product_brand?post=83359"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product_cat?post=83359"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product_tag?post=83359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}