{"id":83140,"date":"2019-05-02T15:23:55","date_gmt":"2019-05-02T14:23:55","guid":{"rendered":"https:\/\/egidimadeinitaly.com\/ecomsite\/product\/andy-warhol-lithography\/"},"modified":"2022-09-07T17:17:06","modified_gmt":"2022-09-07T17:17:06","slug":"andy-warhol-lithograph","status":"publish","type":"product","link":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/","title":{"rendered":"Andy Warhol lithograph"},"content":{"rendered":"<p>Andy Warhol lithograph \u2018<em>Dollar Sign<\/em>\u2018<\/p>\n<p>Year of the edition 1986, certificated by the stamp of the editor on the back of the lithograph.<\/p>\n<p>Limited Edition: 2317\/3000 numbered with pencil on front \/on verso stamped CMOA Carnegie Museum of Art (stamp authenticated)<\/p>\n<p>Signed in the plate, not hand signed by the artist.<\/p>\n<p>The print is a limited edition grano-lithograph-plate signed, is based on an original acrylic on canvas piece called \u201cDollar Sign\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\"><span class=\"s1\">Andy Warhol Lithograph.<\/span><\/p>\n<p class=\"p1\">\n","protected":false},"featured_media":84171,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[6376,6413],"product_tag":[5360],"class_list":["post-83140","product","type-product","status-publish","has-post-thumbnail","product_cat-modern-art","product_cat-modern-work-on-paper-en","product_tag-wall-decorations","first","outofstock","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Andy Warhol lithograph - Egidi MadeinItaly<\/title>\n<meta name=\"description\" content=\"Limited Edition Andy Warhol Lithograph Dollar Sign certificated by the stamp of the editor on the back of the lithograph.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andy Warhol lithograph\" \/>\n<meta property=\"og:description\" content=\"Andy Warhol Lithograph.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/\" \/>\n<meta property=\"og:site_name\" content=\"Egidi MadeinItaly\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/egidimadeinitaly\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-07T17:17:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/egidimadeinitaly.com\/wp-content\/uploads\/2020\/02\/litografia_andy_warhol-e1670579098475.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/\",\"name\":\"Andy Warhol lithograph - Egidi MadeinItaly\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/litografia_andy_warhol-e1670579098475.jpg\",\"datePublished\":\"2019-05-02T14:23:55+00:00\",\"dateModified\":\"2022-09-07T17:17:06+00:00\",\"description\":\"Limited Edition Andy Warhol Lithograph Dollar Sign certificated by the stamp of the editor on the back of the lithograph.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/#primaryimage\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/litografia_andy_warhol-e1670579098475.jpg\",\"contentUrl\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/litografia_andy_warhol-e1670579098475.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Andy Warhol Lithograph Dollar Sign\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/negozio\\\/modern-art\\\/modern-work-on-paper-en\\\/andy-warhol-lithograph\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modern art\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product-category\\\/modern-art\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Modern work on paper\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/product-category\\\/modern-art\\\/modern-work-on-paper-en\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Andy Warhol lithograph\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\",\"name\":\"Egidi MadeinItaly\",\"description\":\"Fine Art\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Andy Warhol lithograph - Egidi MadeinItaly","description":"Limited Edition Andy Warhol Lithograph Dollar Sign certificated by the stamp of the editor on the back of the lithograph.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/","og_locale":"en_US","og_type":"article","og_title":"Andy Warhol lithograph","og_description":"Andy Warhol Lithograph.","og_url":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/","og_site_name":"Egidi MadeinItaly","article_publisher":"https:\/\/www.facebook.com\/egidimadeinitaly\/","article_modified_time":"2022-09-07T17:17:06+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/egidimadeinitaly.com\/wp-content\/uploads\/2020\/02\/litografia_andy_warhol-e1670579098475.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/","url":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/","name":"Andy Warhol lithograph - Egidi MadeinItaly","isPartOf":{"@id":"https:\/\/egidimadeinitaly.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/#primaryimage"},"image":{"@id":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/#primaryimage"},"thumbnailUrl":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2020\/02\/litografia_andy_warhol-e1670579098475.jpg","datePublished":"2019-05-02T14:23:55+00:00","dateModified":"2022-09-07T17:17:06+00:00","description":"Limited Edition Andy Warhol Lithograph Dollar Sign certificated by the stamp of the editor on the back of the lithograph.","breadcrumb":{"@id":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/#primaryimage","url":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2020\/02\/litografia_andy_warhol-e1670579098475.jpg","contentUrl":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2020\/02\/litografia_andy_warhol-e1670579098475.jpg","width":1500,"height":1000,"caption":"Andy Warhol Lithograph Dollar Sign"},{"@type":"BreadcrumbList","@id":"https:\/\/egidimadeinitaly.com\/en\/negozio\/modern-art\/modern-work-on-paper-en\/andy-warhol-lithograph\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egidimadeinitaly.com\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/egidimadeinitaly.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Modern art","item":"https:\/\/egidimadeinitaly.com\/en\/product-category\/modern-art\/"},{"@type":"ListItem","position":4,"name":"Modern work on paper","item":"https:\/\/egidimadeinitaly.com\/en\/product-category\/modern-art\/modern-work-on-paper-en\/"},{"@type":"ListItem","position":5,"name":"Andy Warhol lithograph"}]},{"@type":"WebSite","@id":"https:\/\/egidimadeinitaly.com\/en\/#website","url":"https:\/\/egidimadeinitaly.com\/en\/","name":"Egidi MadeinItaly","description":"Fine Art","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egidimadeinitaly.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product\/83140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/media\/84171"}],"wp:attachment":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/media?parent=83140"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product_brand?post=83140"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product_cat?post=83140"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/product_tag?post=83140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}