{"id":122009,"date":"2025-03-01T07:28:08","date_gmt":"2025-03-01T06:28:08","guid":{"rendered":"https:\/\/egidimadeinitaly.com\/il-mio-account\/"},"modified":"2025-03-03T09:01:58","modified_gmt":"2025-03-03T08:01:58","slug":"my-account","status":"publish","type":"page","link":"https:\/\/egidimadeinitaly.com\/en\/my-account\/","title":{"rendered":"My account"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_custom_heading auto_text=&#8221;yes&#8221; heading_semantic=&#8221;h1&#8243; text_size=&#8221;h1&#8243;]This is a custom heading element.[\/vc_custom_heading][vc_column_text]<div class=\"woocommerce\"><\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading auto_text=&#8221;yes&#8221; heading_semantic=&#8221;h1&#8243; text_size=&#8221;h1&#8243;]This is a custom heading element.[\/vc_custom_heading][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":507,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-122009","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>My account - Egidi MadeinItaly<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egidimadeinitaly.com\/en\/my-account\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"My account\" \/>\n<meta property=\"og:description\" content=\"This is a custom heading element.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egidimadeinitaly.com\/en\/my-account\/\" \/>\n<meta property=\"og:site_name\" content=\"Egidi MadeinItaly\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/egidimadeinitaly\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-03T08:01:58+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/my-account\\\/\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/my-account\\\/\",\"name\":\"My account - Egidi MadeinItaly\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\"},\"datePublished\":\"2025-03-01T06:28:08+00:00\",\"dateModified\":\"2025-03-03T08:01:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/my-account\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/my-account\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/my-account\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"My account\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\",\"name\":\"Egidi MadeinItaly\",\"description\":\"Fine Art\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"My account - Egidi MadeinItaly","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egidimadeinitaly.com\/en\/my-account\/","og_locale":"en_US","og_type":"article","og_title":"My account","og_description":"This is a custom heading element.","og_url":"https:\/\/egidimadeinitaly.com\/en\/my-account\/","og_site_name":"Egidi MadeinItaly","article_publisher":"https:\/\/www.facebook.com\/egidimadeinitaly\/","article_modified_time":"2025-03-03T08:01:58+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egidimadeinitaly.com\/en\/my-account\/","url":"https:\/\/egidimadeinitaly.com\/en\/my-account\/","name":"My account - Egidi MadeinItaly","isPartOf":{"@id":"https:\/\/egidimadeinitaly.com\/en\/#website"},"datePublished":"2025-03-01T06:28:08+00:00","dateModified":"2025-03-03T08:01:58+00:00","breadcrumb":{"@id":"https:\/\/egidimadeinitaly.com\/en\/my-account\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egidimadeinitaly.com\/en\/my-account\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/egidimadeinitaly.com\/en\/my-account\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egidimadeinitaly.com\/en\/"},{"@type":"ListItem","position":2,"name":"My account"}]},{"@type":"WebSite","@id":"https:\/\/egidimadeinitaly.com\/en\/#website","url":"https:\/\/egidimadeinitaly.com\/en\/","name":"Egidi MadeinItaly","description":"Fine Art","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egidimadeinitaly.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/pages\/122009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/users\/507"}],"replies":[{"embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/comments?post=122009"}],"version-history":[{"count":2,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/pages\/122009\/revisions"}],"predecessor-version":[{"id":122065,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/pages\/122009\/revisions\/122065"}],"wp:attachment":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/media?parent=122009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}