{"id":122306,"date":"2025-03-13T11:08:43","date_gmt":"2025-03-13T10:08:43","guid":{"rendered":"https:\/\/egidimadeinitaly.com\/artisti\/renato-natali\/"},"modified":"2025-09-02T09:54:39","modified_gmt":"2025-09-02T08:54:39","slug":"renato-natali","status":"publish","type":"artisti","link":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/","title":{"rendered":"Renato Natali"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><h2>Renato Natali<\/h2>\n<p>[vc_row][vc_column][vc_column_text] Renato Natali (1883-1979) was born into a modest family<\/p>\n<h2>The <em>peintre de la rue<\/em><\/h2>\n<p>He painted views of the city by day and by night, immortalizing its life, including its brawls and prostitutes, so much so that the critics called him &#8220;<em>peintre de la<\/em> <em>rue<\/em>&#8221; and the people of Livorno &#8220;Natali of the nights&#8221;, as the works exhibited in this room attest.<\/p>\n<figure id=\"attachment_122271\" aria-describedby=\"caption-attachment-122271\" style=\"width: 242px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-medium wp-image-122270\" src=\"https:\/\/egidimadeinitaly.com\/wp-content\/uploads\/2025\/03\/Via-della-Madonna-dopo-il-bombardamento-scaled-e1741861289868-242x300.jpg\" alt=\"Renato Natali su Egidi MadeinItaly\" width=\"242\" height=\"300\" \/><figcaption id=\"caption-attachment-122271\" class=\"wp-caption-text\">Via della Madonna dopo il bombardamento<\/figcaption><\/figure>\n<h2>Labronico Group<\/h2>\n<p>In 1920, in Leghorn, he was one of the founders of the Labronico Group, of which he became president in 1977.<\/p>\n<figure id=\"attachment_122267\" aria-describedby=\"caption-attachment-122267\" style=\"width: 206px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-medium wp-image-122266\" src=\"https:\/\/egidimadeinitaly.com\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786.jpg\" alt=\"Renato Natali su Egidi MadeinItaly\" width=\"206\" height=\"300\" srcset=\"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786.jpg 345w, https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786-206x300.jpg 206w\" sizes=\"(max-width: 206px) 100vw, 206px\" \/><figcaption id=\"caption-attachment-122267\" class=\"wp-caption-text\">Renato Natali<\/figcaption><\/figure>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>He painted views of the city by day and by night, capturing everyday life, including brawls and prostitutes.<\/p>\n","protected":false},"featured_media":122267,"parent":0,"template":"","format":"standard","meta":{"_acf_changed":false},"tags":[6505],"class_list":["post-122306","artisti","type-artisti","status-publish","format-standard","has-post-thumbnail","hentry","tags-n"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Renato Natali - Egidi MadeinItaly<\/title>\n<meta name=\"description\" content=\"Renato Natali (1883-1979), a self-taught Leghorn painter, painted the popular and nocturnal life of Leghorn. Member of the Labronico Group.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renato Natali\" \/>\n<meta property=\"og:description\" content=\"He painted views of the city by day and by night, capturing everyday life, including brawls and prostitutes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/\" \/>\n<meta property=\"og:site_name\" content=\"Egidi MadeinItaly\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/egidimadeinitaly\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-02T08:54:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1472\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/\",\"name\":\"Renato Natali - Egidi MadeinItaly\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Renato-Natali-ritratto-scaled-e1741860323786.jpg\",\"datePublished\":\"2025-03-13T10:08:43+00:00\",\"dateModified\":\"2025-09-02T08:54:39+00:00\",\"description\":\"Renato Natali (1883-1979), a self-taught Leghorn painter, painted the popular and nocturnal life of Leghorn. Member of the Labronico Group.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Renato-Natali-ritratto-scaled-e1741860323786.jpg\",\"contentUrl\":\"https:\\\/\\\/egidimadeinitaly.com\\\/v25\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Renato-Natali-ritratto-scaled-e1741860323786.jpg\",\"width\":1472,\"height\":2560,\"caption\":\"Renato Natali ritratto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/artisti\\\/renato-natali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renato Natali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/\",\"name\":\"Egidi MadeinItaly\",\"description\":\"Fine Art\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egidimadeinitaly.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Renato Natali - Egidi MadeinItaly","description":"Renato Natali (1883-1979), a self-taught Leghorn painter, painted the popular and nocturnal life of Leghorn. Member of the Labronico Group.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/","og_locale":"en_US","og_type":"article","og_title":"Renato Natali","og_description":"He painted views of the city by day and by night, capturing everyday life, including brawls and prostitutes.","og_url":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/","og_site_name":"Egidi MadeinItaly","article_publisher":"https:\/\/www.facebook.com\/egidimadeinitaly\/","article_modified_time":"2025-09-02T08:54:39+00:00","og_image":[{"width":1472,"height":2560,"url":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/","url":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/","name":"Renato Natali - Egidi MadeinItaly","isPartOf":{"@id":"https:\/\/egidimadeinitaly.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/#primaryimage"},"image":{"@id":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/#primaryimage"},"thumbnailUrl":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786.jpg","datePublished":"2025-03-13T10:08:43+00:00","dateModified":"2025-09-02T08:54:39+00:00","description":"Renato Natali (1883-1979), a self-taught Leghorn painter, painted the popular and nocturnal life of Leghorn. Member of the Labronico Group.","breadcrumb":{"@id":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/#primaryimage","url":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786.jpg","contentUrl":"https:\/\/egidimadeinitaly.com\/v25\/wp-content\/uploads\/2025\/03\/Renato-Natali-ritratto-scaled-e1741860323786.jpg","width":1472,"height":2560,"caption":"Renato Natali ritratto"},{"@type":"BreadcrumbList","@id":"https:\/\/egidimadeinitaly.com\/en\/artisti\/renato-natali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egidimadeinitaly.com\/en\/"},{"@type":"ListItem","position":2,"name":"Renato Natali"}]},{"@type":"WebSite","@id":"https:\/\/egidimadeinitaly.com\/en\/#website","url":"https:\/\/egidimadeinitaly.com\/en\/","name":"Egidi MadeinItaly","description":"Fine Art","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egidimadeinitaly.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/artisti\/122306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/artisti"}],"about":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/types\/artisti"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/media\/122267"}],"wp:attachment":[{"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/media?parent=122306"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/tags?post=122306"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/egidimadeinitaly.com\/en\/wp-json\/wp\/v2\/tags?post=122306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}